{"id":14403,"date":"2024-06-11T11:42:59","date_gmt":"2024-06-11T09:42:59","guid":{"rendered":"https:\/\/blogdelarechercheclinique.com\/?p=14403"},"modified":"2025-04-11T14:18:20","modified_gmt":"2025-04-11T12:18:20","slug":"seisme-invalidation-privacy-shield-recherche-clinique","status":"publish","type":"post","link":"https:\/\/blogdelarechercheclinique.com\/en\/seisme-invalidation-privacy-shield-recherche-clinique\/","title":{"rendered":"Le s\u00e9isme: invalidation du privacy shield et recherche clinique"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><iframe data-src=\"https:\/\/www.youtube.com\/embed\/4tgunLKle5g\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<p>Le s\u00e9isme: invalidation du Privacy Shield et recherche clinique<\/p>\n\n\n<p><em>Si vous souhaitez des outils de travail, ou vous former, ou \u00eatre coacher, ou une r\u00e9ponse d&rsquo;un juriste ou&nbsp;participer \u00e0 des webinaires \u00e0 ce sujet, rendez-vous sur<\/em> <a href=\"http:\/\/www.pharmaspecific-training.com\">www.pharmaspecific-training.com<\/a><\/p>\n\n\n\n<p>si vous souhaitez de l&rsquo;aide sur le RGPD au sein de votre structure, rendez-vous sur <a href=\"http:\/\/www.pharmaspecific.com\">www.pharmaspecific.com<\/a><\/p>\n\n\n\n<p>Transcription texte : Bonjour \u00e0 tous, c&rsquo;est Manon Durand, juriste sant\u00e9 au sein de l&rsquo;entreprise Pharmaspecific. Aujourd&rsquo;hui, on va aborder le th\u00e8me de la protection des donn\u00e9es personnelles \u00e0 travers l&rsquo;<a href=\"https:\/\/blogdelarechercheclinique.com\/en\/\"><strong>invalidation du privacy shield<\/strong><\/a>.<\/p>\n\n\n\n<p>Puisque vous n&rsquo;avez pas pu passer \u00e0 c\u00f4t\u00e9 cette information, le&nbsp;privacy shield a&nbsp;r\u00e9cemment \u00e9t\u00e9 invalid\u00e9e par la cour de justice de l&rsquo;union europ\u00e9enne. Avant de commencer, je vous rappelle que vous pouvez retrouver l&rsquo;ensemble de nos veilles juridiques sur notre site Pharmaspecific training pour vous tenir inform\u00e9 de l&rsquo;actualit\u00e9 dans le domaine de la recherche clinique.<\/p>\n\n\n\n<p>Si vous avez une question d&rsquo;ordre juridique, vous pouvez \u00e9galement me solliciter \u00e0 ce sujet sur la m\u00eame plateforme pour obtenir une r\u00e9ponse. On commence donc tout de suite sur le sujet du jour.<\/p>\n\n\n\n<p>Pour rappel, le&nbsp;privacy shield&nbsp;ou bouclier de protection des donn\u00e9es \u00e9tait en accord dans le domaine du droit de la protection des donn\u00e9es personnelles n\u00e9goci\u00e9 entre 2015 et 2016 entre l&rsquo;union europ\u00e9enne d&rsquo;une part, et les&nbsp;\u00c9tats-Unis d&rsquo;Am\u00e9rique d&rsquo;autre part. Le&nbsp;privacy shield&nbsp;se composait d&rsquo;une s\u00e9rie de dispositions qui r\u00e9glementait la protection des donn\u00e9es personnelles qui \u00e9taient transf\u00e9r\u00e9es depuis un \u00e9tat membre de l&rsquo;union vers les&nbsp;\u00c9tats-Unis,&nbsp;ce qui permettait en fait de transf\u00e9rer des donn\u00e9es sans avoir besoin de recourir aux diff\u00e9rents m\u00e9canismes de protection qui sont pr\u00e9vus aujourd&rsquo;hui par le RGPD. Notamment, les clauses contractuelles types, les binding corporates rooms etc &#8230;<\/p>\n\n\n\n<p>Le&nbsp;privacy shield&nbsp;avait d&rsquo;ailleurs \u00e9t\u00e9 lui-m\u00eame mis en place \u00e0 la suite de l&rsquo;<strong><a title=\"R\u00e9union en recherche clinique\" href=\"https:\/\/blogdelarechercheclinique.com\/en\/reunion-recherche-clinique-gratuite-a-ne-manquer\/\">invalidation du safe harbor<\/a><\/strong> par la cour de justice de l&rsquo;union europ\u00e9enne, qui en octobre 2015 avait rendu une premi\u00e8re d\u00e9cision dans laquelle elle estimait que le safe harbor ne permettait pas d&rsquo;assurer un niveau de protection ad\u00e9quate.&nbsp;\u00c0&nbsp;la suite de cette d\u00e9cision, le&nbsp;privacy shield&nbsp;a donc \u00e9t\u00e9 mis en place afin de pallier aux d\u00e9faillances du safe harbor puisqu&rsquo;il est venu ajouter des garanties suppl\u00e9mentaires pour les personnes concern\u00e9es.<\/p>\n\n\n\n<p>Mais la cour de justice a estim\u00e9 dans un arr\u00eat rendu le 16 juillet 2020 que le m\u00e9canisme du&nbsp;privacy shield&nbsp;ne permettait pas non plus de pallier les limitations du droit am\u00e9ricain. Selon elle, le <a href=\"https:\/\/blogdelarechercheclinique.com\/en\/\"><strong>syst\u00e8me du&nbsp;privacy shield<\/strong><\/a>&nbsp;n&rsquo;\u00e9tait pas suffisamment ind\u00e9pendant vis-\u00e0-vis du pouvoir ex\u00e9cutif am\u00e9ricain puisque les autorit\u00e9s publiques am\u00e9ricaines peuvent avoir acc\u00e8s et utiliser les donn\u00e9es personnelles qui sont transf\u00e9r\u00e9es depuis l&rsquo;union europ\u00e9enne. Tout cela d\u00e9coule en r\u00e9alit\u00e9 du fait de l&rsquo;adoption du cloud act en 2018 qui est une loi qui donne en fait toute l\u00e9gitimit\u00e9 aux entreprises am\u00e9ricaines de transf\u00e9rer les donn\u00e9es de leurs clients ind\u00e9pendamment de leur territoire d&rsquo;h\u00e9bergement \u00e0 tout juge am\u00e9ricain qui en ferait la demande sans que son propri\u00e9taire ni son pays de r\u00e9sidence ou le pays qui stocke les donn\u00e9es en soit inform\u00e9.<\/p>\n\n\n\n<p>La cour de justice consid\u00e8re que ces acc\u00e8s et utilisation par les autorit\u00e9s am\u00e9ricaines ne r\u00e9pondent donc pas \u00e0 des exigences \u00e9quivalentes \u00e0 celles attendues en droit de l&rsquo;union europ\u00e9enne par ce qu&rsquo;on appelle le principe de proportionnalit\u00e9 car les programmes de surveillance fond\u00e9e sur la r\u00e9glementation am\u00e9ricaine ne sont pas limit\u00e9s au strict n\u00e9cessaire.<\/p>\n\n\n\n<p>Donc, puisque <a href=\"https:\/\/blogdelarechercheclinique.com\/en\/\"><strong>le dispositif du&nbsp;privacy shield<\/strong><\/a>&nbsp;ne permet pas d&rsquo;assurer un niveau de protection ad\u00e9quate, la d\u00e9cision d&rsquo;ad\u00e9quation rendu en 2016 a alors \u00e9t\u00e9 annul\u00e9e par la cour de justice et les transferts de donn\u00e9es personnelles ne peuvent donc plus \u00eatre op\u00e9r\u00e9s librement vers des organismes qui sont situ\u00e9s sur le sol des&nbsp;\u00c9tats-Unis&nbsp;m\u00eame s&rsquo;il s&rsquo;agit d&rsquo;adh\u00e9rents au&nbsp;privacy shield.<\/p>\n\n\n\n<p>Alors, si vous devez op\u00e9rer un transfert de donn\u00e9es \u00e0 caract\u00e8re personnel vers une entreprise situ\u00e9e sur le sol am\u00e9ricain, vous devez vous munir de garanties suffisantes, notamment \u00e0 l&rsquo;aide des diff\u00e9rents outils mis en place par le RGPD. En tant que chef de projet clinique, plusieurs v\u00e9rifications sont donc \u00e0 faire. Premi\u00e8rement, il est n\u00e9cessaire pour vous de faire un bilan des donn\u00e9es personnelles qui peuvent relever de ce cas de figure, notamment, dans les cas o\u00f9 vous utilisez des outils dont l&rsquo;h\u00e9bergement est op\u00e9r\u00e9 sur les territoires des \u00c9tats-Unis.<\/p>\n\n\n\n<p>Vous devez d&rsquo;ailleurs \u00eatre vigilant sur ce point parce que m\u00eame les grosses plateformes comme Microsoft sont concern\u00e9es par ces nouvelles r\u00e8gles. Vous devez donc vous renseigner sur les mesures adopt\u00e9es par les h\u00e9bergeurs de tous vos outils de travail et v\u00e9rifier si leurs <strong>politiques de protection des donn\u00e9es personnelles<\/strong> sont adapt\u00e9s aux exigences du RGPD et si ce n&rsquo;est pas le cas, vous tourner vers des solutions europ\u00e9ennes. Ensuite, si vous \u00eates en lien avec une \u00e9tude clinique dont le promoteur est situ\u00e9 aux \u00c9tats-Unis, vous devez vous assurer qu&rsquo;aucun transfert de donn\u00e9es qui seront recueillies dans l&rsquo;union europ\u00e9enne comme les donn\u00e9es patient contenues dans les cahiers d&rsquo;observation par exemple ne sont op\u00e9r\u00e9es vers les \u00c9tats-Unis sans avoir mis en place des clauses contractuelles types avec ce promoteur.<\/p>\n\n\n\n<p>Ces clauses contractuelles devront \u00eatre tr\u00e8s pr\u00e9cises sur les mesures adopt\u00e9es pour garantir la s\u00e9curit\u00e9 du transfert et je vous recommande d&rsquo;ailleurs fortement de mettre en place une solution de cryptage pour de tels transferts. Vous avez \u00e9galement le site de la CNIL qui propose des mod\u00e8les de clauses contractuelles types qui pourront vous servir de base pour mettre en place cet outil. Enfin, vous devez prendre contact avec le DPO de votre soci\u00e9t\u00e9 afin de modifier les diff\u00e9rents documents qui sont requis par la&nbsp;CNIL. Comme par exemple, les registres de traitement et les analyses d&rsquo;impact pour les mettre en conformit\u00e9 avec les nouvelles mesures que vous aurez adopt\u00e9es.<\/p>\n\n\n\n<p>Voil\u00e0, vous \u00eates maintenant inform\u00e9s des raisons de l&rsquo;invalidation du&nbsp;privacy shield&nbsp;et des cons\u00e9quences pour votre entreprise et votre \u00e9tude clinique. Pour toutes informations suppl\u00e9mentaires, n&rsquo;h\u00e9sitez pas \u00e0 vous reporter \u00e0 nos veilles juridiques ou \u00e0 me solliciter pour un conseil juridique.<\/p>\n\n\n\n<p>Merci \u00e0 vous d&rsquo;avoir \u00e9cout\u00e9 ce podcast et n&rsquo;h\u00e9sitez pas \u00e0 le partager \u00e0 ceux qui pourraient \u00eatre int\u00e9ress\u00e9s par ce sujet. Quant \u00e0 nous, on se retrouve bient\u00f4t pour un nouveau podcast.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui, on va aborder le th\u00e8me de la protection des donn\u00e9es personnelles \u00e0 travers l&rsquo;invalidation du privacy shield.<\/p>","protected":false},"author":4,"featured_media":14404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_122143508198123560_331463380343150":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[390],"tags":[],"class_list":{"0":"post-14403","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-jeux-evenements"},"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le s\u00e9isme: Invalidation du Privacy Shield et recherche clinique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogdelarechercheclinique.com\/en\/seisme-invalidation-privacy-shield-recherche-clinique\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le s\u00e9isme: invalidation du privacy shield et recherche clinique -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogdelarechercheclinique.com\/en\/seisme-invalidation-privacy-shield-recherche-clinique\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogdelarechercheclinique\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-11T09:42:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-11T12:18:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/invalidation-privacy-shield.png\" \/>\n\t<meta property=\"og:image:width\" content=\"552\" \/>\n\t<meta property=\"og:image:height\" content=\"307\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Vanessa Montanari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vanessa Montanari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/\"},\"author\":{\"name\":\"Vanessa Montanari\",\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/#\\\/schema\\\/person\\\/13ee3f7a1251afe7e98918a482685938\"},\"headline\":\"Le s\u00e9isme: invalidation du privacy shield et recherche clinique\",\"datePublished\":\"2024-06-11T09:42:59+00:00\",\"dateModified\":\"2025-04-11T12:18:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/\"},\"wordCount\":1214,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogdelarechercheclinique.com\\\/blog-contenu\\\/uploads\\\/2024\\\/06\\\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1\",\"articleSection\":[\"Jeux - \u00e9v\u00e8nements\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/\",\"url\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/\",\"name\":\"Le s\u00e9isme: Invalidation du Privacy Shield et recherche clinique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogdelarechercheclinique.com\\\/blog-contenu\\\/uploads\\\/2024\\\/06\\\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1\",\"datePublished\":\"2024-06-11T09:42:59+00:00\",\"dateModified\":\"2025-04-11T12:18:20+00:00\",\"description\":\"On va aborder le th\u00e8me de la protection des donn\u00e9es personnelles \u00e0 travers l'invalidation du privacy shield.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogdelarechercheclinique.com\\\/blog-contenu\\\/uploads\\\/2024\\\/06\\\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogdelarechercheclinique.com\\\/blog-contenu\\\/uploads\\\/2024\\\/06\\\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1\",\"width\":552,\"height\":307,\"caption\":\"Privacy shield\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/seisme-invalidation-privacy-shield-recherche-clinique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le s\u00e9isme: invalidation du privacy shield et recherche clinique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/#website\",\"url\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/\",\"name\":\"Blog de la recherche clinique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/#organization\",\"name\":\"Blog de la recherche clinique\",\"url\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/blogdelarechercheclinique.com\\\/blog-contenu\\\/uploads\\\/2024\\\/04\\\/cropped-BLOG-logo.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/blogdelarechercheclinique.com\\\/blog-contenu\\\/uploads\\\/2024\\\/04\\\/cropped-BLOG-logo.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Blog de la recherche clinique\"},\"image\":{\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/blogdelarechercheclinique\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/#\\\/schema\\\/person\\\/13ee3f7a1251afe7e98918a482685938\",\"name\":\"Vanessa Montanari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddf428208f542d6c2239ace6606ebe9beb71049642a9c784967f23e4e76e8efc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddf428208f542d6c2239ace6606ebe9beb71049642a9c784967f23e4e76e8efc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddf428208f542d6c2239ace6606ebe9beb71049642a9c784967f23e4e76e8efc?s=96&d=mm&r=g\",\"caption\":\"Vanessa Montanari\"},\"url\":\"https:\\\/\\\/blogdelarechercheclinique.com\\\/en\\\/author\\\/vanessa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le s\u00e9isme: Invalidation du Privacy Shield et recherche clinique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogdelarechercheclinique.com\/en\/seisme-invalidation-privacy-shield-recherche-clinique\/","og_locale":"en_US","og_type":"article","og_title":"Le s\u00e9isme: invalidation du privacy shield et recherche clinique -","og_url":"https:\/\/blogdelarechercheclinique.com\/en\/seisme-invalidation-privacy-shield-recherche-clinique\/","article_publisher":"https:\/\/www.facebook.com\/blogdelarechercheclinique","article_published_time":"2024-06-11T09:42:59+00:00","article_modified_time":"2025-04-11T12:18:20+00:00","og_image":[{"width":552,"height":307,"url":"https:\/\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/invalidation-privacy-shield.png","type":"image\/png"}],"author":"Vanessa Montanari","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Vanessa Montanari","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/#article","isPartOf":{"@id":"https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/"},"author":{"name":"Vanessa Montanari","@id":"https:\/\/blogdelarechercheclinique.com\/#\/schema\/person\/13ee3f7a1251afe7e98918a482685938"},"headline":"Le s\u00e9isme: invalidation du privacy shield et recherche clinique","datePublished":"2024-06-11T09:42:59+00:00","dateModified":"2025-04-11T12:18:20+00:00","mainEntityOfPage":{"@id":"https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/"},"wordCount":1214,"commentCount":0,"publisher":{"@id":"https:\/\/blogdelarechercheclinique.com\/#organization"},"image":{"@id":"https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1","articleSection":["Jeux - \u00e9v\u00e8nements"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/","url":"https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/","name":"Le s\u00e9isme: Invalidation du Privacy Shield et recherche clinique","isPartOf":{"@id":"https:\/\/blogdelarechercheclinique.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/#primaryimage"},"image":{"@id":"https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1","datePublished":"2024-06-11T09:42:59+00:00","dateModified":"2025-04-11T12:18:20+00:00","description":"On va aborder le th\u00e8me de la protection des donn\u00e9es personnelles \u00e0 travers l'invalidation du privacy shield.","breadcrumb":{"@id":"https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/#primaryimage","url":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1","width":552,"height":307,"caption":"Privacy shield"},{"@type":"BreadcrumbList","@id":"https:\/\/blogdelarechercheclinique.com\/seisme-invalidation-privacy-shield-recherche-clinique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blogdelarechercheclinique.com\/"},{"@type":"ListItem","position":2,"name":"Le s\u00e9isme: invalidation du privacy shield et recherche clinique"}]},{"@type":"WebSite","@id":"https:\/\/blogdelarechercheclinique.com\/#website","url":"https:\/\/blogdelarechercheclinique.com\/","name":"Blog de la recherche clinique","description":"","publisher":{"@id":"https:\/\/blogdelarechercheclinique.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogdelarechercheclinique.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blogdelarechercheclinique.com\/#organization","name":"Blog de la recherche clinique","url":"https:\/\/blogdelarechercheclinique.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogdelarechercheclinique.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/04\/cropped-BLOG-logo.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/04\/cropped-BLOG-logo.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Blog de la recherche clinique"},"image":{"@id":"https:\/\/blogdelarechercheclinique.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blogdelarechercheclinique"]},{"@type":"Person","@id":"https:\/\/blogdelarechercheclinique.com\/#\/schema\/person\/13ee3f7a1251afe7e98918a482685938","name":"Vanessa Montanari","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ddf428208f542d6c2239ace6606ebe9beb71049642a9c784967f23e4e76e8efc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ddf428208f542d6c2239ace6606ebe9beb71049642a9c784967f23e4e76e8efc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ddf428208f542d6c2239ace6606ebe9beb71049642a9c784967f23e4e76e8efc?s=96&d=mm&r=g","caption":"Vanessa Montanari"},"url":"https:\/\/blogdelarechercheclinique.com\/en\/author\/vanessa\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1","jetpack-related-posts":[{"id":12758,"url":"https:\/\/blogdelarechercheclinique.com\/en\/cadre-transatlantique-transfert-donnees-clinique\/","url_meta":{"origin":14403,"position":0},"title":"CADRE TRANSATLANTIQUE: TRANSFERT DE DONN\u00c9ES CLINIQUE","author":"Vanessa Montanari","date":"13 November 2023","format":false,"excerpt":"A l\u2019aube des ann\u00e9es 2000,\u202fun ensemble de principes appel\u00e9 \u00ab\u202fSafe Harbor\u202f\u00bb, avait \u00e9t\u00e9 mis en place afin de permettre \u00e0 certaines entreprises am\u00e9ricaines de certifier qu\u2019elles \u00e9taient conformes \u00e0 la l\u00e9gislation de l\u2019Union europ\u00e9enne. Cette certification leur permettait donc d\u2019obtenir l\u2019autorisation de transfert pour les donn\u00e9es cliniques de l\u2019Union europ\u00e9enne\u2026","rel":"","context":"In &quot;Les r\u00e8glementaires&quot;","block_context":{"text":"Les r\u00e8glementaires","link":"https:\/\/blogdelarechercheclinique.com\/en\/category\/reglementaires\/"},"img":{"alt_text":"Le cadre transatlantique et son histoire de protection de donn\u00e9es","src":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2023\/11\/Data-transfert.png?fit=848%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2023\/11\/Data-transfert.png?fit=848%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2023\/11\/Data-transfert.png?fit=848%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2023\/11\/Data-transfert.png?fit=848%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":11536,"url":"https:\/\/blogdelarechercheclinique.com\/en\/invalidating-privacy-shield-clinical-researc\/","url_meta":{"origin":14403,"position":1},"title":"The earthquake:  Invalidating the Privacy Shield and clinical research (Now, what?)","author":"Vanessa Montanari","date":"22 November 2020","format":false,"excerpt":"Hello everyone, this is Manon Durand, health lawyer with Pharmaspecific. Today, we are going to talk about the protection of personal data through the invalidation of the privacy shield.","rel":"","context":"In &quot;Clinical Research News&quot;","block_context":{"text":"Clinical Research News","link":"https:\/\/blogdelarechercheclinique.com\/en\/category\/clinical-research-news\/"},"img":{"alt_text":"Privacy shield","src":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/invalidation-privacy-shield.png?fit=552%2C307&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":13931,"url":"https:\/\/blogdelarechercheclinique.com\/en\/safe-harbor-transfert-donnees-personnelles\/","url_meta":{"origin":14403,"position":2},"title":"Safe Harbor : transfert de donn\u00e9es personnelles non valid\u00e9","author":"Vanessa Montanari","date":"4 November 2015","format":false,"excerpt":"Savais tu que l\u2019accord commercial reliant l\u2019Espace Economique Europ\u00e9en et les Etats-Unis avait \u00e9t\u00e9 invalid\u00e9 et que les transferts de donn\u00e9es personnelles r\u00e9alis\u00e9s dans le cadre du Safe Harbor n\u2019\u00e9taient plus autoris\u00e9s ? Voici concr\u00e8tement ce que cela implique pour tes essais.","rel":"","context":"In &quot;Les r\u00e8glementaires&quot;","block_context":{"text":"Les r\u00e8glementaires","link":"https:\/\/blogdelarechercheclinique.com\/en\/category\/reglementaires\/"},"img":{"alt_text":"Invalidation safe harbor","src":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/05\/safe-harbor.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14350,"url":"https:\/\/blogdelarechercheclinique.com\/en\/tec-obligations-rgpd\/","url_meta":{"origin":14403,"position":3},"title":"TEC : Mise en place des obligations li\u00e9es au RGPD","author":"Vanessa Montanari","date":"10 June 2024","format":false,"excerpt":"On se retrouve aujourd\u2019hui une nouvelle fois pour parler du RGPD, le R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es. Je vous rappelle, ce texte sert de r\u00e9f\u00e9rence en mati\u00e8re de protection des donn\u00e9es \u00e0 caract\u00e8re personnel au sein de l\u2019UE. Il est entr\u00e9 en application le 25 mai 2018 dans\u2026","rel":"","context":"In &quot;Les r\u00e8glementaires&quot;","block_context":{"text":"Les r\u00e8glementaires","link":"https:\/\/blogdelarechercheclinique.com\/en\/category\/reglementaires\/"},"img":{"alt_text":"Technicien en \u00e9tude clinique","src":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/TEC.png?fit=550%2C307&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/TEC.png?fit=550%2C307&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/TEC.png?fit=550%2C307&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":11679,"url":"https:\/\/blogdelarechercheclinique.com\/en\/suppression-donnees-demande-patient\/","url_meta":{"origin":14403,"position":4},"title":"RGPD : Suppression de donn\u00e9es \u00e0 la demande du patient?","author":"Vanessa Montanari","date":"21 April 2021","format":false,"excerpt":"On se retrouve encore pour parler du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (le RGPD). Ce dernier est entr\u00e9 en application au sein de l\u2019Union Europ\u00e9enne le 25 mai 2018.","rel":"","context":"In &quot;Les r\u00e8glementaires&quot;","block_context":{"text":"Les r\u00e8glementaires","link":"https:\/\/blogdelarechercheclinique.com\/en\/category\/reglementaires\/"},"img":{"alt_text":"RGPD : Suppression de donn\u00e9es \u00e0 la demande du patient?","src":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2021\/04\/RGPD-suppression-donnees.png?fit=555%2C308&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2021\/04\/RGPD-suppression-donnees.png?fit=555%2C308&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2021\/04\/RGPD-suppression-donnees.png?fit=555%2C308&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":14368,"url":"https:\/\/blogdelarechercheclinique.com\/en\/rgpd-certification-conformite-processus-entreprise\/","url_meta":{"origin":14403,"position":5},"title":"RGPD: Certification et conformit\u00e9 des processus en entreprise","author":"Vanessa Montanari","date":"10 June 2024","format":false,"excerpt":"Le RGPD est le texte de r\u00e9f\u00e9rence en mati\u00e8re de protection des donn\u00e9es \u00e0 caract\u00e8re personnel. Il est entr\u00e9 en application au sein de l\u2019Union Europ\u00e9enne le 25 mai 2018.","rel":"","context":"In &quot;Les r\u00e8glementaires&quot;","block_context":{"text":"Les r\u00e8glementaires","link":"https:\/\/blogdelarechercheclinique.com\/en\/category\/reglementaires\/"},"img":{"alt_text":"Certification RGPD","src":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/Certification-RGPD.png?fit=552%2C307&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/Certification-RGPD.png?fit=552%2C307&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdelarechercheclinique.com\/blog-contenu\/uploads\/2024\/06\/Certification-RGPD.png?fit=552%2C307&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogdelarechercheclinique.com\/en\/wp-json\/wp\/v2\/posts\/14403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdelarechercheclinique.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdelarechercheclinique.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdelarechercheclinique.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdelarechercheclinique.com\/en\/wp-json\/wp\/v2\/comments?post=14403"}],"version-history":[{"count":3,"href":"https:\/\/blogdelarechercheclinique.com\/en\/wp-json\/wp\/v2\/posts\/14403\/revisions"}],"predecessor-version":[{"id":15031,"href":"https:\/\/blogdelarechercheclinique.com\/en\/wp-json\/wp\/v2\/posts\/14403\/revisions\/15031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdelarechercheclinique.com\/en\/wp-json\/wp\/v2\/media\/14404"}],"wp:attachment":[{"href":"https:\/\/blogdelarechercheclinique.com\/en\/wp-json\/wp\/v2\/media?parent=14403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdelarechercheclinique.com\/en\/wp-json\/wp\/v2\/categories?post=14403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdelarechercheclinique.com\/en\/wp-json\/wp\/v2\/tags?post=14403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}